{"id":135,"count":1,"description":"","link":"https:\/\/etherealwebsolution.com\/sq\/tag\/rritja-e-angazhimit-te-perdoruesve\/","name":"Rritja e angazhimit t\u00eb p\u00ebrdoruesve","slug":"rritja-e-angazhimit-te-perdoruesve","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/etherealwebsolution.com\/sq\/wp-json\/wp\/v2\/tags\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etherealwebsolution.com\/sq\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/etherealwebsolution.com\/sq\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/etherealwebsolution.com\/sq\/wp-json\/wp\/v2\/posts?tags=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}